{"id":1036,"date":"2010-08-16T19:18:14","date_gmt":"2010-08-16T17:18:14","guid":{"rendered":"http:\/\/www.bkits.at\/weblog\/?p=1036"},"modified":"2010-08-24T12:56:29","modified_gmt":"2010-08-24T10:56:29","slug":"das-drogenkarnickel","status":"publish","type":"post","link":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/","title":{"rendered":"Das Drogenkarnickel"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"content\/images\/general\/german.gif\" alt=\"\" width=\"17\" height=\"10\" \/> Es gibt Dinge auf dieser Welt, die sind so unglaublich, dass sie schon wieder wahr sein k&#246;nnten &#8211; auch ohne Drogenkonsum. M&#246;ge sich der geneigte Leser sein eigenes Bild errauchen&#8230; Zum <a title=\"Link zum Originalartikel\" href=\"http:\/\/salzburg.orf.at\/stories\/463149\/\" target=\"_blank\">Drogensuchkaninchen<\/a>.<\/p>\n<p>PS: Nebenbei ist das einer der bestgeschriebensten Artikel, die man auf den ORF L&#228;nderseiten in den letzten Jahren finden konnte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt Dinge auf dieser Welt, die sind so unglaublich, dass sie schon wieder wahr sein k&#246;nnten &#8211; auch ohne Drogenkonsum. M&#246;ge sich der geneigte Leser sein eigenes Bild errauchen&#8230; Zum Drogensuchkaninchen. PS: Nebenbei ist das einer der bestgeschriebensten Artikel, &hellip; <a href=\"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1036","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das Drogenkarnickel - Berni&#039;s ~page V5 Weblog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das Drogenkarnickel - Berni&#039;s ~page V5 Weblog\" \/>\n<meta property=\"og:description\" content=\"Es gibt Dinge auf dieser Welt, die sind so unglaublich, dass sie schon wieder wahr sein k&#246;nnten &#8211; auch ohne Drogenkonsum. M&#246;ge sich der geneigte Leser sein eigenes Bild errauchen&#8230; Zum Drogensuchkaninchen. PS: Nebenbei ist das einer der bestgeschriebensten Artikel, &hellip; Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/\" \/>\n<meta property=\"og:site_name\" content=\"Berni&#039;s ~page V5 Weblog\" \/>\n<meta property=\"article:published_time\" content=\"2010-08-16T17:18:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-08-24T10:56:29+00:00\" \/>\n<meta name=\"author\" content=\"Berni\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/\"},\"author\":{\"name\":\"Berni\",\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/#\\\/schema\\\/person\\\/61421026f67d1bc90a5c3588df6aab09\"},\"headline\":\"Das Drogenkarnickel\",\"datePublished\":\"2010-08-16T17:18:14+00:00\",\"dateModified\":\"2010-08-24T10:56:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/\"},\"wordCount\":57,\"commentCount\":0,\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/\",\"url\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/\",\"name\":\"Das Drogenkarnickel - Berni&#039;s ~page V5 Weblog\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/#website\"},\"datePublished\":\"2010-08-16T17:18:14+00:00\",\"dateModified\":\"2010-08-24T10:56:29+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/#\\\/schema\\\/person\\\/61421026f67d1bc90a5c3588df6aab09\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/2010\\\/08\\\/16\\\/das-drogenkarnickel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das Drogenkarnickel\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/#website\",\"url\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/\",\"name\":\"Berni&#039;s ~page V5 Weblog\",\"description\":\"The official weblog to Berni&#039;s ~page V5\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/#\\\/schema\\\/person\\\/61421026f67d1bc90a5c3588df6aab09\",\"name\":\"Berni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bbe1da1bb1567ae15d978ea1d968c0b6b6a84cc9e9ba34d9b5dc7594e79c099?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bbe1da1bb1567ae15d978ea1d968c0b6b6a84cc9e9ba34d9b5dc7594e79c099?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bbe1da1bb1567ae15d978ea1d968c0b6b6a84cc9e9ba34d9b5dc7594e79c099?s=96&d=mm&r=g\",\"caption\":\"Berni\"},\"url\":\"http:\\\/\\\/www.bkits.at\\\/weblog\\\/author\\\/berni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das Drogenkarnickel - Berni&#039;s ~page V5 Weblog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/","og_locale":"de_DE","og_type":"article","og_title":"Das Drogenkarnickel - Berni&#039;s ~page V5 Weblog","og_description":"Es gibt Dinge auf dieser Welt, die sind so unglaublich, dass sie schon wieder wahr sein k&#246;nnten &#8211; auch ohne Drogenkonsum. M&#246;ge sich der geneigte Leser sein eigenes Bild errauchen&#8230; Zum Drogensuchkaninchen. PS: Nebenbei ist das einer der bestgeschriebensten Artikel, &hellip; Weiterlesen &rarr;","og_url":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/","og_site_name":"Berni&#039;s ~page V5 Weblog","article_published_time":"2010-08-16T17:18:14+00:00","article_modified_time":"2010-08-24T10:56:29+00:00","author":"Berni","twitter_misc":{"Verfasst von":"Berni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/#article","isPartOf":{"@id":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/"},"author":{"name":"Berni","@id":"http:\/\/www.bkits.at\/weblog\/#\/schema\/person\/61421026f67d1bc90a5c3588df6aab09"},"headline":"Das Drogenkarnickel","datePublished":"2010-08-16T17:18:14+00:00","dateModified":"2010-08-24T10:56:29+00:00","mainEntityOfPage":{"@id":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/"},"wordCount":57,"commentCount":0,"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/","url":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/","name":"Das Drogenkarnickel - Berni&#039;s ~page V5 Weblog","isPartOf":{"@id":"http:\/\/www.bkits.at\/weblog\/#website"},"datePublished":"2010-08-16T17:18:14+00:00","dateModified":"2010-08-24T10:56:29+00:00","author":{"@id":"http:\/\/www.bkits.at\/weblog\/#\/schema\/person\/61421026f67d1bc90a5c3588df6aab09"},"breadcrumb":{"@id":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.bkits.at\/weblog\/2010\/08\/16\/das-drogenkarnickel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/www.bkits.at\/weblog\/"},{"@type":"ListItem","position":2,"name":"Das Drogenkarnickel"}]},{"@type":"WebSite","@id":"http:\/\/www.bkits.at\/weblog\/#website","url":"http:\/\/www.bkits.at\/weblog\/","name":"Berni&#039;s ~page V5 Weblog","description":"The official weblog to Berni&#039;s ~page V5","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.bkits.at\/weblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/www.bkits.at\/weblog\/#\/schema\/person\/61421026f67d1bc90a5c3588df6aab09","name":"Berni","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6bbe1da1bb1567ae15d978ea1d968c0b6b6a84cc9e9ba34d9b5dc7594e79c099?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bbe1da1bb1567ae15d978ea1d968c0b6b6a84cc9e9ba34d9b5dc7594e79c099?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bbe1da1bb1567ae15d978ea1d968c0b6b6a84cc9e9ba34d9b5dc7594e79c099?s=96&d=mm&r=g","caption":"Berni"},"url":"http:\/\/www.bkits.at\/weblog\/author\/berni\/"}]}},"_links":{"self":[{"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/posts\/1036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/comments?post=1036"}],"version-history":[{"count":2,"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/posts\/1036\/revisions"}],"predecessor-version":[{"id":1050,"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/posts\/1036\/revisions\/1050"}],"wp:attachment":[{"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/media?parent=1036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/categories?post=1036"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.bkits.at\/weblog\/wp-json\/wp\/v2\/tags?post=1036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}